{"id":282,"date":"2018-10-06T11:23:42","date_gmt":"2018-10-06T09:23:42","guid":{"rendered":"http:\/\/massimiliano-granieri.unibs.it\/?p=282"},"modified":"2018-10-06T11:23:48","modified_gmt":"2018-10-06T09:23:48","slug":"giornata-di-studi-in-onore-di-roberto-pardolesi","status":"publish","type":"post","link":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/2018\/10\/06\/giornata-di-studi-in-onore-di-roberto-pardolesi\/","title":{"rendered":"Giornata di studi in onore di Roberto Pardolesi"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Il prossimo 5 novembre, alla LUISS Guido Carli, ci sar\u00e0 una giornata di studi dedicata a Roberto Pardolesi. Come si conviene quando un professore universitario va fuori ruolo per raggiunti limiti di et\u00e0, Francesco Di Ciommo e Onofrio Troiano con grande dedizione e passione hanno raccolto una serie di scritti in suo onore, che saranno consegnati alla fine della giornata.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Roberto Pardolesi professore universitario va in pensione. Roberto Pardolesi Maestro resta in servizio permanente effettivo; il suo magistero ha sempre fatto a meno di investiture formali. La sua mentorship &#8211; come si direbbe altrove &#8211; , vale a dire la sua vocazione a guidare le ricerca, stimolare la curiosit\u00e0 intellettuale, revocare in dubbio le certezze marmoree della scienza giuridica e costruirne altre, \u00e8 stata una dote innata, che non aveva un prima e non avr\u00e0 un dopo. E la generosit\u00e0 con la quale ha accolto generazioni di studenti, divenuti poi avvocati, magistrati, manager, professori a loro volta, credo abbia pochi eguali nella storia recente dell&#8217;Universit\u00e0 italiana.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per chi lo conosce da vicino, Roberto Pardolesi \u00e8 stato molto pi\u00f9 che una guida scientifica e un Maestro. E&#8217; stato un amico, un fratello maggiore, un padre, all&#8217;Universit\u00e0, come al Foro italiano, come nelle vite di tutti i giorni, quando i percorsi umani e familiari si intrecciano con le vicende professionali, ricordandoci che prima di tutto siamo persone e che, proprio per questo, dobbiamo sempre tenere la schiena diritta e tener fede alle cose in cui crediamo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un giorno a Foggia, alla fine di un convegno, ho sentito rivolgere al prof. Pardolesi uno dei complimenti pi\u00f9 belli e raffinati che un altro collega potesse formulare. Dopo una relazione di quelle per le quali serviva una doppia bombola d&#8217;ossigeno anche soltanto per ascoltarla, Antonio Padoa Schioppa lo salut\u00f2 dicendo: &#8220;Roberto, sei un incendiario di cervelli&#8221;. Al nostro Maestro piromane, che non ha smesso un giorno di dar da mangiare alle nostre menti, rivolgo il mio augurio per la giornata di studi e per tutto quello (ancora molto) che Roberto Pardolesi Maestro far\u00e0 insieme alla sua Scuola.\u00a0<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"789\" height=\"1134\" src=\"https:\/\/massimiliano-granieri.unibs.it\/wp-content\/uploads\/2018\/10\/image.png\" alt=\"\" class=\"wp-image-283\" srcset=\"https:\/\/massimiliano-granieri.unibs.it\/wp-content\/uploads\/2018\/10\/image.png 789w, https:\/\/massimiliano-granieri.unibs.it\/wp-content\/uploads\/2018\/10\/image-209x300.png 209w, https:\/\/massimiliano-granieri.unibs.it\/wp-content\/uploads\/2018\/10\/image-768x1104.png 768w, https:\/\/massimiliano-granieri.unibs.it\/wp-content\/uploads\/2018\/10\/image-712x1024.png 712w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il prossimo 5 novembre, alla LUISS Guido Carli, ci sar\u00e0 una giornata di studi dedicata a Roberto Pardolesi. Come si conviene quando un professore universitario va fuori ruolo per raggiunti limiti di et\u00e0, Francesco Di Ciommo e Onofrio Troiano con grande dedizione e passione hanno raccolto una serie di scritti in suo onore, che saranno &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/massimiliano-granieri.unibs.it\/index.php\/2018\/10\/06\/giornata-di-studi-in-onore-di-roberto-pardolesi\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Giornata di studi in onore di Roberto Pardolesi&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-282","post","type-post","status-publish","format-standard","hentry","category-senza-categoria"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9zVyC-4y","_links":{"self":[{"href":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/wp-json\/wp\/v2\/posts\/282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/wp-json\/wp\/v2\/comments?post=282"}],"version-history":[{"count":1,"href":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/wp-json\/wp\/v2\/posts\/282\/revisions"}],"predecessor-version":[{"id":284,"href":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/wp-json\/wp\/v2\/posts\/282\/revisions\/284"}],"wp:attachment":[{"href":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/wp-json\/wp\/v2\/media?parent=282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/wp-json\/wp\/v2\/categories?post=282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/wp-json\/wp\/v2\/tags?post=282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}