{"id":402,"date":"2019-10-04T17:59:17","date_gmt":"2019-10-04T15:59:17","guid":{"rendered":"http:\/\/massimiliano-granieri.unibs.it\/?p=402"},"modified":"2019-10-04T17:59:17","modified_gmt":"2019-10-04T15:59:17","slug":"nuove-prospettive-nella-tutela-della-proprieta-intellettuale-nellindustria-4-0-a-unimore","status":"publish","type":"post","link":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/2019\/10\/04\/nuove-prospettive-nella-tutela-della-proprieta-intellettuale-nellindustria-4-0-a-unimore\/","title":{"rendered":"Nuove prospettive nella tutela della propriet\u00e0 intellettuale nell&#8217;Industria 4.0 a #UNIMORE"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">L&#8217;Universit\u00e0 di Modena e Reggio Emilia e il suo ILO hanno organizzato un ciclo di seminari dedicati alla Terza Missione delle Universit\u00e0: prospettive e scenari futuri. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E&#8217; previsto un seminario sulla propriet\u00e0 intellettuale. Qui di seguito \u00e8 riportato il programma. La lista completa dei seminari \u00e8 disponibile a questo <a href=\"https:\/\/www.unimore.it\/terzamissione\/\"><strong><em>link<\/em><\/strong><\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gioved\u00ec 17 ottobre 2019, ore 9:30<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fondazione Marco Biagi &#8211; Largo Marco Biagi, 10 Modena<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Programma<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>09:30 &#8211; 10:00<br><strong>Registrazione partecipanti<\/strong><\/li><li>10:00 &#8211; 10:10<br><strong>Saluti di benvenuto e apertura dei lavori<\/strong><br>Marcello Pellicciari Delegato Terza Missione &#8211; Unimore,<br>Modera<br>Giulia Catellani (Direzione Ricerca, Trasferimento Tecnologico e Terza Missione &#8211; ILO &#8211; Unimore)<\/li><li>10:10 &#8211; 10:40<br><strong>L&#8217;organizzazione a supporto della protezione e valorizzazione delle PI: un&#8217;esperienza locale e il panorama universitario nazionale<\/strong><br>Giuseppe Conti (Responsabile di ARIC UNIBO, Direttivo Netval)<\/li><li>10:40 &#8211; 11:10<br><strong>Industria 4.0: le tecnologie abilitanti della quarta rivoluzione industriale<\/strong><br>Cesare Fantuzzi (rappresentante Unimore in Cluster nazionale Fabbrica Intelligente e Competence Center)<\/li><li>11:10 &#8211; 11:40<br><strong>Industria 4.0: competitivit\u00e0 nazionale e propriet\u00e0 intellettuale<\/strong><br>Massimiliano Granieri (UNIBS, membro Giunta Netval)<\/li><li>11:40 &#8211; 12:00<br><strong>Pausa caff\u00e8<\/strong><\/li><li>12:00 &#8211; 12:30<br><strong>Industria 4.0: la ricerca di documentazione brevettuale per l&#8217;innovazione<\/strong><br>Guido Moradei (AIDB &#8211; Associazione Italiana Documentalisti Brevettuali)<\/li><li>12:30 &#8211; 13:00<br><strong>Industria 4.0: innovazione e forme di tutela P.I.<\/strong><br>Paolo Garavelli (Consulente in Propriet\u00e0 Industriale &#8211; Mandatario Europeo)<br>Andrea Castaldo (Consulente in Propriet\u00e0 Industriale)<\/li><li>13:00 &#8211; 13:30<br><strong>Industria 4.0: tutela del Know-How alla luce del D.lgs. 63\/18<\/strong><br>Giovanni Cavani (Presidente Commissione brevetti Unimore)<\/li><li>13:30 &#8211; 13:30<br><strong>Chiusura dei lavori<\/strong><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Universit\u00e0 di Modena e Reggio Emilia e il suo ILO hanno organizzato un ciclo di seminari dedicati alla Terza Missione delle Universit\u00e0: prospettive e scenari futuri. E&#8217; previsto un seminario sulla propriet\u00e0 intellettuale. Qui di seguito \u00e8 riportato il programma. La lista completa dei seminari \u00e8 disponibile a questo link. Gioved\u00ec 17 ottobre 2019, ore &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/massimiliano-granieri.unibs.it\/index.php\/2019\/10\/04\/nuove-prospettive-nella-tutela-della-proprieta-intellettuale-nellindustria-4-0-a-unimore\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Nuove prospettive nella tutela della propriet\u00e0 intellettuale nell&#8217;Industria 4.0 a #UNIMORE&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-402","post","type-post","status-publish","format-standard","hentry","category-senza-categoria"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9zVyC-6u","_links":{"self":[{"href":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/wp-json\/wp\/v2\/posts\/402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/wp-json\/wp\/v2\/comments?post=402"}],"version-history":[{"count":1,"href":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/wp-json\/wp\/v2\/posts\/402\/revisions"}],"predecessor-version":[{"id":403,"href":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/wp-json\/wp\/v2\/posts\/402\/revisions\/403"}],"wp:attachment":[{"href":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/wp-json\/wp\/v2\/media?parent=402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/wp-json\/wp\/v2\/categories?post=402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/wp-json\/wp\/v2\/tags?post=402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}