{"id":408,"date":"2019-10-10T22:07:40","date_gmt":"2019-10-10T20:07:40","guid":{"rendered":"http:\/\/massimiliano-granieri.unibs.it\/?p=408"},"modified":"2019-10-10T22:07:40","modified_gmt":"2019-10-10T20:07:40","slug":"seminario-formativo-netval-codau-crui-definiamo-la-terza-missione","status":"publish","type":"post","link":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/2019\/10\/10\/seminario-formativo-netval-codau-crui-definiamo-la-terza-missione\/","title":{"rendered":"Seminario formativo #Netval #Codau #CRUI: Definiamo la Terza Missione"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>Strategie, modelli, organizzazione e strumenti per massimizzare la valorizzazione della conoscenza e l\u2019impatto sulla societ\u00e0<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Fondazione CRUI, CODAU e NETVAL hanno organizzato un seminario formativo, che si terr\u00e0 a <strong>Roma, 14 e 15 ottobre 2019  in <\/strong> <strong>|<a href=\"https:\/\/goo.gl\/maps\/mzF92x9TD8H2vMzQ6\"> Roma Piazza Rondanini<\/a><\/strong><a href=\"https:\/\/goo.gl\/maps\/mzF92x9TD8H2vMzQ6\"> 48 <\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Maggiori informazioni sono disponibili <a href=\"https:\/\/www.fondazionecrui.it\/archivio-corsi-e-seminari\/14-e-15-ottobre-2019-definiamo-la-terza-missione\/\">qui<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il tema del trasferimento tecnologico \u00e8 ormai evoluto in un concetto pi\u00f9 ampio di terza missione, stabilmente oggetto di azioni e politiche, nonch\u00e9 di attivit\u00e0 quotidiana e progettualit\u00e0 nelle universit\u00e0 e negli Enti Pubblici di Ricerca italiani ma non ancora definita pienamente e compiutamente .<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tra i molti interventi che sono necessari per colmare il gap rimanente, figura la formazione. Occorre infatti maggiore impegno per aggiornare le competenze ed allineare i comportamenti operativi di docenti, personale tecnico-amministrativo, policy makers, ecc. A tale proposito, considerandolo come parte dei propri compiti statutari, Fondazione CRUI, Netval e CODAU hanno deciso di offrire il presente percorso formativo destinato ai Delegati del Rettore e ai responsabili amministrativi e gestionali, figure chiave nei dipartimenti universitari, e ai dirigenti e funzionari negli enti pubblici di ricerca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destinatari del percorso formativo sono le nuove figure di Delegati del Rettore nei vari ambiti toccati dalla Terza Missione, le nuove figure professionali Tecnico-Amministrative gestionali che hanno la responsabilit\u00e0 di dipartimenti universitari o di strutture equivalenti negli enti pubblici di ricerca. \u00c8 comunque aperta la partecipazione anche ad altre persone che lavorano nella struttura amministrativa di universit\u00e0 ed enti pubblici di ricerca.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Strategie, modelli, organizzazione e strumenti per massimizzare la valorizzazione della conoscenza e l\u2019impatto sulla societ\u00e0 Fondazione CRUI, CODAU e NETVAL hanno organizzato un seminario formativo, che si terr\u00e0 a Roma, 14 e 15 ottobre 2019 in | Roma Piazza Rondanini 48 Maggiori informazioni sono disponibili qui. Il tema del trasferimento tecnologico \u00e8 ormai evoluto in &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/massimiliano-granieri.unibs.it\/index.php\/2019\/10\/10\/seminario-formativo-netval-codau-crui-definiamo-la-terza-missione\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Seminario formativo #Netval #Codau #CRUI: Definiamo la Terza Missione&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-408","post","type-post","status-publish","format-standard","hentry","category-senza-categoria"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9zVyC-6A","_links":{"self":[{"href":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/wp-json\/wp\/v2\/posts\/408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/wp-json\/wp\/v2\/comments?post=408"}],"version-history":[{"count":1,"href":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/wp-json\/wp\/v2\/posts\/408\/revisions"}],"predecessor-version":[{"id":409,"href":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/wp-json\/wp\/v2\/posts\/408\/revisions\/409"}],"wp:attachment":[{"href":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/wp-json\/wp\/v2\/media?parent=408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/wp-json\/wp\/v2\/categories?post=408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/massimiliano-granieri.unibs.it\/index.php\/wp-json\/wp\/v2\/tags?post=408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}